{"id":676,"date":"2022-04-07T11:03:28","date_gmt":"2022-04-07T11:03:28","guid":{"rendered":"https:\/\/ydentic.com\/vacancies\/"},"modified":"2022-04-15T14:32:17","modified_gmt":"2022-04-15T14:32:17","slug":"vacatures","status":"publish","type":"page","link":"https:\/\/ydentic.com\/nl\/vacatures\/","title":{"rendered":"Werken bij Ydentic"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"archive-ocj_vacancies.php","meta":{"footnotes":""},"class_list":["post-676","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Werken bij Ydentic - Ydentic<\/title>\n<meta name=\"description\" content=\"Ons software\u00adplatform helpt toonaangevende bedrijven effici\u00ebnter te werken. Help jij ons daarbij?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ydentic.com\/nl\/vacatures\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Werken bij Ydentic - Ydentic\" \/>\n<meta property=\"og:description\" content=\"Ons software\u00adplatform helpt toonaangevende bedrijven effici\u00ebnter te werken. Help jij ons daarbij?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ydentic.com\/nl\/vacatures\/\" \/>\n<meta property=\"og:site_name\" content=\"Ydentic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ydentic\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-15T14:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ydentic.com\/wp-content\/uploads\/2022\/04\/ydentic-website-launch-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ydentic\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/vacatures\\\/\",\"url\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/vacatures\\\/\",\"name\":\"Werken bij Ydentic - Ydentic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/#website\"},\"datePublished\":\"2022-04-07T11:03:28+00:00\",\"dateModified\":\"2022-04-15T14:32:17+00:00\",\"description\":\"Ons software\u00adplatform helpt toonaangevende bedrijven effici\u00ebnter te werken. Help jij ons daarbij?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/vacatures\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ydentic.com\\\/nl\\\/vacatures\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/vacatures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Werken bij Ydentic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/\",\"name\":\"Ydentic\",\"description\":\"Some description\",\"publisher\":{\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/#organization\",\"name\":\"Ydentic\",\"url\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ydentic.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ydentic-logo-black.png\",\"contentUrl\":\"https:\\\/\\\/ydentic.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ydentic-logo-black.png\",\"width\":261,\"height\":40,\"caption\":\"Ydentic\"},\"image\":{\"@id\":\"https:\\\/\\\/ydentic.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ydentic\",\"https:\\\/\\\/x.com\\\/ydentic\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ydentic\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Werken bij Ydentic - Ydentic","description":"Ons software\u00adplatform helpt toonaangevende bedrijven effici\u00ebnter te werken. Help jij ons daarbij?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ydentic.com\/nl\/vacatures\/","og_locale":"nl_NL","og_type":"article","og_title":"Werken bij Ydentic - Ydentic","og_description":"Ons software\u00adplatform helpt toonaangevende bedrijven effici\u00ebnter te werken. Help jij ons daarbij?","og_url":"https:\/\/ydentic.com\/nl\/vacatures\/","og_site_name":"Ydentic","article_publisher":"https:\/\/www.facebook.com\/ydentic","article_modified_time":"2022-04-15T14:32:17+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/ydentic.com\/wp-content\/uploads\/2022\/04\/ydentic-website-launch-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ydentic","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ydentic.com\/nl\/vacatures\/","url":"https:\/\/ydentic.com\/nl\/vacatures\/","name":"Werken bij Ydentic - Ydentic","isPartOf":{"@id":"https:\/\/ydentic.com\/nl\/#website"},"datePublished":"2022-04-07T11:03:28+00:00","dateModified":"2022-04-15T14:32:17+00:00","description":"Ons software\u00adplatform helpt toonaangevende bedrijven effici\u00ebnter te werken. Help jij ons daarbij?","breadcrumb":{"@id":"https:\/\/ydentic.com\/nl\/vacatures\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ydentic.com\/nl\/vacatures\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ydentic.com\/nl\/vacatures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ydentic.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Werken bij Ydentic"}]},{"@type":"WebSite","@id":"https:\/\/ydentic.com\/nl\/#website","url":"https:\/\/ydentic.com\/nl\/","name":"Ydentic","description":"Some description","publisher":{"@id":"https:\/\/ydentic.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ydentic.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/ydentic.com\/nl\/#organization","name":"Ydentic","url":"https:\/\/ydentic.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/ydentic.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/ydentic.com\/wp-content\/uploads\/2022\/04\/ydentic-logo-black.png","contentUrl":"https:\/\/ydentic.com\/wp-content\/uploads\/2022\/04\/ydentic-logo-black.png","width":261,"height":40,"caption":"Ydentic"},"image":{"@id":"https:\/\/ydentic.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ydentic","https:\/\/x.com\/ydentic","https:\/\/www.linkedin.com\/company\/ydentic\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/pages\/676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/comments?post=676"}],"version-history":[{"count":1,"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/pages\/676\/revisions"}],"predecessor-version":[{"id":677,"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/pages\/676\/revisions\/677"}],"wp:attachment":[{"href":"https:\/\/ydentic.com\/nl\/wp-json\/wp\/v2\/media?parent=676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}